{"id":4322,"date":"2023-01-16T09:42:34","date_gmt":"2023-01-16T08:42:34","guid":{"rendered":"https:\/\/radioactivegaming.eu\/?p=4322"},"modified":"2023-01-16T10:14:13","modified_gmt":"2023-01-16T09:14:13","slug":"patchnotes-16-jan-2023","status":"publish","type":"post","link":"https:\/\/radioactivegaming.eu\/de_de\/2023\/01\/16\/patchnotes-16-jan-2023\/","title":{"rendered":"Patchnotes 16.Jan.2023"},"content":{"rendered":"\n<p>Stegarion:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Der Stegarion ist nun endlich released!<br>Er hat eine besondere Tamemechanik, welche ihr selber herausfinden m\u00fcsst!<br>Ihr findet ihn auf einigen Powerstone Inseln!<br>Er eignet sich besonders gut als &#8222;Tank&#8220; da er mit seinem Shielding sehr gut Schaden absorbieren kann.<br>Durch seine Heilskill ist es ihm m\u00f6glich schnell wieder einem Kampf beizutreten<\/p>\n<\/blockquote>\n\n\n\n<p><strong>Rebalancing:<\/strong><br>B\u00e4ren:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Base Health reduziert<\/li>\n\n\n\n<li>Base Stamina reduziert<\/li>\n\n\n\n<li>Melee Prozent\/Level reduziert<\/li>\n<\/ul>\n\n\n\n<p>Yeti:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reitet ihr den Yeti werdet ihr vor den schlimmsten Effekten des Blizzards gesch\u00fctzt<\/li>\n\n\n\n<li>Schaden der Yetis ist stark erh\u00f6ht bei Temperaturen unter 0 Grad<\/li>\n\n\n\n<li>Neue Attacke die es m\u00f6glich macht Fasern zu sammeln<\/li>\n<\/ul>\n\n\n\n<p>Thorny Dragon:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reitet ihr den Thorny Dragon werdet ihr vor den schlimmsten Effekten des Sandsturms gesch\u00fctzt<\/li>\n\n\n\n<li>Verringerter eingehender Schaden bei Temperaturen &gt; 30 Grad<\/li>\n<\/ul>\n\n\n\n<p>K\u00fche &amp; Bullen:<br>K\u00f6nnen nun den Cargo- &amp; Carriage-Sattel tragen<\/p>\n\n\n\n<p>Beastmastery:<br>Feat Courage &#8211; Macht euer Tier kurzzeitig immun gegen Furcht und entfernt diese sogar.<br>Kostet 12 Attributpunkte<br>Kostet beim aktivieren 150 Stamina<br>Cooldown: 90 Sekunden<br>Dauer: 15 Sekunden<\/p>\n\n\n\n<p>Manned Cannons &amp; Large Cannons:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Im PvP lassen sich f\u00fcr Ship Cannons &amp; Large Cannons nun NPCs &#8222;kaufen&#8220; wenn sich diese auf Land befinden. (30g pro NPC)<\/li>\n<\/ul>\n\n\n\n<p><strong>\u00dcberarbeitung Magiesystem:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Magie wird nicht mehr im Stab gespeichert sondern nach dem wirken abgefeuert<\/li>\n\n\n\n<li>Mana wird w\u00e4hrend des Minigames verbraucht (Hit = 25 Mana, Miss = 50 Mana, Keine Aktion = 30 Mana)<\/li>\n\n\n\n<li>Das Minigame l\u00e4uft nun immer komplett durch<\/li>\n\n\n\n<li>Best\u00e4tigung des MiniGames mit Rechtsklick<\/li>\n\n\n\n<li>Nach dem Verbraucht von Mana wird 1 Sek kein Mana regeneriert<\/li>\n\n\n\n<li>Casten wird mit Linksklick unterbrochen (nur Channeling Spells)<\/li>\n\n\n\n<li>Bei Channeling Spells wird nach dem Wirken best\u00e4ndig Mana verbraucht, dass Minigame verbraucht nun immer X Mana, egal ob das Minigame gespielt wird oder nicht<\/li>\n\n\n\n<li>Der Mana Verbrauch bei Channeling Spells l\u00e4sst sich berechnen:<\/li>\n<\/ul>\n\n\n\n<p>X = Anzahl der n\u00f6tigen Minispiele zum Wirken x 2<br>Ein Channeling Spell der Advanced Stufe verbraucht so beispielsweise 6&#215;2, also 12 Mana pro durchlaufendem Minispiel.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Minigame wird nur noch mit Rechtsklick best\u00e4tigt<\/li>\n\n\n\n<li>Das Minigame zeigt an wie viele Minigames verbleiben bevor der Zauber gewirkt wird.<\/li>\n\n\n\n<li>Zauber werden in ihre Klassen geteilt:<\/li>\n\n\n\n<li>Wasser<\/li>\n\n\n\n<li>Wind (Zauber folgen sp\u00e4ter)<\/li>\n\n\n\n<li>Erde<\/li>\n\n\n\n<li>Feuer<\/li>\n\n\n\n<li>Barrier (Zauber folgen sp\u00e4ter)<\/li>\n\n\n\n<li>Healing (Zauber folgen sp\u00e4ter)<\/li>\n\n\n\n<li>Magie ist nun in verschiedene Stufen eingeteilt:<\/li>\n\n\n\n<li>Elementary 2x Minigame<\/li>\n\n\n\n<li>Intermediate 4x Minigame<\/li>\n\n\n\n<li>Advanced 6x Minigame<\/li>\n\n\n\n<li>Saint 8x Minigame (Vorerst nicht wirkbar)<\/li>\n\n\n\n<li>King 10x Minigame (Vorerst nicht wirkbar)<\/li>\n\n\n\n<li>Imperial (nur mit Ritualkreis) (Vorerst nicht wirkbar)<\/li>\n<\/ul>\n\n\n\n<p>In einem Sp\u00e4teren Update wird es ebenfalls M\u00f6glich sein Zauber zu kombinieren!<\/p>\n\n\n\n<p>Was passiert wenn mir das Mana w\u00e4hrend einem Zauber ausgeht?<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Wenn euch das Mana w\u00e4hrend dem Wirken eines Zaubers ausgeht, formt sich dieser nicht.<\/p>\n<\/blockquote>\n\n\n\n<p>Manatr\u00e4nke:<br>Manatr\u00e4nke k\u00f6nnen aus Mythos, Wasser, Herbs und Flasks produziert werden.<br>Flasks produziert ihr im Smelter aus Sand, dabei erhaltet ihr immer 15 Flaschen<br>Ihr k\u00f6nnt keine Manatr\u00e4nke konsumieren w\u00e4hrend ihr einen Zauber wirkt!<\/p>\n\n\n\n<p>Alle Tiere:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Es ist nicht mehr m\u00f6glich Tiere zu unclaimen<\/li>\n<\/ul>\n\n\n\n<p>Tierverkaufsplattform:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die TVK kostet nur noch 5g alle 2 Stunden und damit nur 60g pro Tag<\/li>\n\n\n\n<li>Es k\u00f6nnen bis zu 10 Tiere Angeboten werden<\/li>\n\n\n\n<li>Pro Tier werden beim Verkauf 2,5% Provision f\u00e4llig<\/li>\n<\/ul>\n\n\n\n<p>Anti Dumping:<\/p>\n\n\n\n<p>TVK Plattformen lassen nun gewisse preise bei Tieren nicht mehr zu.<br>Dabei handelt es sich nicht um Orientierungswerte, sondern absolute Minimum Werte, welche nicht unterschritten werden k\u00f6nnen<br>Diese Errechnen sich aus dem Geburtslevel und der gew\u00e4hlten Ressource<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stegarion: Der Stegarion ist nun endlich released!Er hat eine besondere Tamemechanik, welche ihr selber herausfinden m\u00fcsst!Ihr findet ihn auf einigen Powerstone Inseln!Er eignet sich besonders gut als &#8222;Tank&#8220; da er mit seinem Shielding sehr gut Schaden absorbieren kann.Durch seine Heilskill ist es ihm m\u00f6glich schnell wieder einem Kampf beizutreten Rebalancing:B\u00e4ren: Yeti: Thorny Dragon: K\u00fche &amp;&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/radioactivegaming.eu\/de_de\/2023\/01\/16\/patchnotes-16-jan-2023\/\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4322","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Patchnotes 16.Jan.2023 - Radioactive Gaming<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patchnotes 16.Jan.2023 - Radioactive Gaming\" \/>\n<meta property=\"og:description\" content=\"Stegarion: Der Stegarion ist nun endlich released!Er hat eine besondere Tamemechanik, welche ihr selber herausfinden m\u00fcsst!Ihr findet ihn auf einigen Powerstone Inseln!Er eignet sich besonders gut als &#8222;Tank&#8220; da er mit seinem Shielding sehr gut Schaden absorbieren kann.Durch seine Heilskill ist es ihm m\u00f6glich schnell wieder einem Kampf beizutreten Rebalancing:B\u00e4ren: Yeti: Thorny Dragon: K\u00fche &amp;&hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioactivegaming.eu\/de_de\/2023\/01\/16\/patchnotes-16-jan-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Radioactive Gaming\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-16T08:42:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-16T09:14:13+00:00\" \/>\n<meta name=\"author\" content=\"Revy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Revy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/\"},\"author\":{\"name\":\"Revy\",\"@id\":\"https:\/\/radioactivegaming.eu\/#\/schema\/person\/a8c72e8c1c18daea65fea134dbbf1cb2\"},\"headline\":\"Patchnotes 16.Jan.2023\",\"datePublished\":\"2023-01-16T08:42:34+00:00\",\"dateModified\":\"2023-01-16T09:14:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/\"},\"wordCount\":552,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/radioactivegaming.eu\/#organization\"},\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/\",\"url\":\"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/\",\"name\":\"Patchnotes 16.Jan.2023 - Radioactive Gaming\",\"isPartOf\":{\"@id\":\"https:\/\/radioactivegaming.eu\/#website\"},\"datePublished\":\"2023-01-16T08:42:34+00:00\",\"dateModified\":\"2023-01-16T09:14:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/radioactivegaming.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patchnotes 16.Jan.2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radioactivegaming.eu\/#website\",\"url\":\"https:\/\/radioactivegaming.eu\/\",\"name\":\"Radioactive Gaming\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/radioactivegaming.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radioactivegaming.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radioactivegaming.eu\/#organization\",\"name\":\"Radioactive Gaming\",\"url\":\"https:\/\/radioactivegaming.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/radioactivegaming.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radioactivegaming.eu\/wp-content\/uploads\/2019\/12\/cropped-coin-2.png\",\"contentUrl\":\"https:\/\/radioactivegaming.eu\/wp-content\/uploads\/2019\/12\/cropped-coin-2.png\",\"width\":256,\"height\":256,\"caption\":\"Radioactive Gaming\"},\"image\":{\"@id\":\"https:\/\/radioactivegaming.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCHAH-p_vfp_co-__TB4M14A\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radioactivegaming.eu\/#\/schema\/person\/a8c72e8c1c18daea65fea134dbbf1cb2\",\"name\":\"Revy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/radioactivegaming.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b6a507162b11615ebef27393f601bc4d014a4ef64b819f00b17693d154a78a1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b6a507162b11615ebef27393f601bc4d014a4ef64b819f00b17693d154a78a1?s=96&d=mm&r=g\",\"caption\":\"Revy\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patchnotes 16.Jan.2023 - Radioactive Gaming","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Patchnotes 16.Jan.2023 - Radioactive Gaming","og_description":"Stegarion: Der Stegarion ist nun endlich released!Er hat eine besondere Tamemechanik, welche ihr selber herausfinden m\u00fcsst!Ihr findet ihn auf einigen Powerstone Inseln!Er eignet sich besonders gut als &#8222;Tank&#8220; da er mit seinem Shielding sehr gut Schaden absorbieren kann.Durch seine Heilskill ist es ihm m\u00f6glich schnell wieder einem Kampf beizutreten Rebalancing:B\u00e4ren: Yeti: Thorny Dragon: K\u00fche &amp;&hellip; Read more","og_url":"https:\/\/radioactivegaming.eu\/de_de\/2023\/01\/16\/patchnotes-16-jan-2023\/","og_site_name":"Radioactive Gaming","article_published_time":"2023-01-16T08:42:34+00:00","article_modified_time":"2023-01-16T09:14:13+00:00","author":"Revy","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Revy","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/#article","isPartOf":{"@id":"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/"},"author":{"name":"Revy","@id":"https:\/\/radioactivegaming.eu\/#\/schema\/person\/a8c72e8c1c18daea65fea134dbbf1cb2"},"headline":"Patchnotes 16.Jan.2023","datePublished":"2023-01-16T08:42:34+00:00","dateModified":"2023-01-16T09:14:13+00:00","mainEntityOfPage":{"@id":"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/"},"wordCount":552,"commentCount":2,"publisher":{"@id":"https:\/\/radioactivegaming.eu\/#organization"},"articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/","url":"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/","name":"Patchnotes 16.Jan.2023 - Radioactive Gaming","isPartOf":{"@id":"https:\/\/radioactivegaming.eu\/#website"},"datePublished":"2023-01-16T08:42:34+00:00","dateModified":"2023-01-16T09:14:13+00:00","breadcrumb":{"@id":"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/radioactivegaming.eu\/2023\/01\/16\/patchnotes-16-jan-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/radioactivegaming.eu\/"},{"@type":"ListItem","position":2,"name":"Patchnotes 16.Jan.2023"}]},{"@type":"WebSite","@id":"https:\/\/radioactivegaming.eu\/#website","url":"https:\/\/radioactivegaming.eu\/","name":"Radioactive Gaming","description":"","publisher":{"@id":"https:\/\/radioactivegaming.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioactivegaming.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/radioactivegaming.eu\/#organization","name":"Radioactive Gaming","url":"https:\/\/radioactivegaming.eu\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/radioactivegaming.eu\/#\/schema\/logo\/image\/","url":"https:\/\/radioactivegaming.eu\/wp-content\/uploads\/2019\/12\/cropped-coin-2.png","contentUrl":"https:\/\/radioactivegaming.eu\/wp-content\/uploads\/2019\/12\/cropped-coin-2.png","width":256,"height":256,"caption":"Radioactive Gaming"},"image":{"@id":"https:\/\/radioactivegaming.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCHAH-p_vfp_co-__TB4M14A"]},{"@type":"Person","@id":"https:\/\/radioactivegaming.eu\/#\/schema\/person\/a8c72e8c1c18daea65fea134dbbf1cb2","name":"Revy","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/radioactivegaming.eu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b6a507162b11615ebef27393f601bc4d014a4ef64b819f00b17693d154a78a1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b6a507162b11615ebef27393f601bc4d014a4ef64b819f00b17693d154a78a1?s=96&d=mm&r=g","caption":"Revy"}}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/posts\/4322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/comments?post=4322"}],"version-history":[{"count":4,"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/posts\/4322\/revisions"}],"predecessor-version":[{"id":4326,"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/posts\/4322\/revisions\/4326"}],"wp:attachment":[{"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/media?parent=4322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/categories?post=4322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioactivegaming.eu\/de_de\/wp-json\/wp\/v2\/tags?post=4322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}